{"id":674,"date":"2012-04-04T08:25:05","date_gmt":"2012-04-04T06:25:05","guid":{"rendered":"http:\/\/schilddruesenguide.de\/thyreoiditis\/?p=674"},"modified":"2026-04-25T07:41:38","modified_gmt":"2026-04-25T05:41:38","slug":"brittas-diaet-tagebuch-abnehmen-mit-hashimoto-thyreoiditis","status":"publish","type":"post","link":"https:\/\/schilddruesenguide.de\/thyreoiditis\/brittas-diaet-tagebuch-abnehmen-mit-hashimoto-thyreoiditis\/","title":{"rendered":"Britta&#8217;s Di\u00e4t-Tagebuch \u2013 Abnehmen mit Hashimoto-Thyreoiditis"},"content":{"rendered":"<p>Alle auf www.schilddruesenguide.de bisher ver\u00f6ffentlichten Erfahrungsberichte von Hashimoto-Patientinnen: <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/glaubt-an-euch-kaempft-fuer-eure-gesundheit-und-wehrt-euch\/\">Andrea<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/die-goldene-dosis-oder-auf-der-suche-nach-dem-unmoeglichen-traum\/\">Annette<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/barbaras-erfahrungsbericht-hashimoto-thyreoiditis\/\">Barbara<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/brittas-diaet-tagebuch-abnehmen-mit-hashimoto-thyreoiditis\/\">Britta<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/katjas-erfahrungsbericht-abnehmen-mit-hashimoto-thyreoiditis\/\">Katja<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/saras-erfahrungsbericht-i-in-meinem-leben-spielt-hashimoto-kaum-noch-eine-rolle\/\">Sara<\/a>, <a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/susannes-erfahrungsbericht-hashimoto-thyreoiditis\/\">Susanne<\/a> &#8211; falls sie auch bereit sind Ihre Geschichte aufzuschreiben, melden Sie sich gern per E-Mail.<!--more--><\/p>\n<p style=\"text-align: center;\">-Anzeige-<br \/>\n<script async src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-2860650483659473\" crossorigin=\"anonymous\"><\/script><br \/>\n<!-- SDG-2025-Display-Responsiv --><br \/>\n<ins class=\"adsbygoogle\" style=\"display: block;\" data-ad-client=\"ca-pub-2860650483659473\" data-ad-slot=\"5199025168\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins><br \/>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<h2><strong>Shopping-Frust statt Shopping-Lust <\/strong><\/h2>\n<p><strong>16.02.12 <\/strong>Hallo, ich bin Britta, 37 Jahre alt, verheiratet und Hausfrau. Ich habe eine Hashimoto-Thyreoiditis und nehme deswegen auch schon seit mehreren Jahren Schilddr\u00fcsenhormone ein. Damit geht es mir ganz gut, obwohl ich manchmal das Gef\u00fchl habe meine Gesundheit ist seit der Diagnose eine Dauerbaustelle. Irgendetwas ist halt immer \u2026 Momentan ist das Gewicht wieder mal ein Thema f\u00fcr mich. Dabei war ich immer normalgewichtig. Nicht so klapperd\u00fcrr wie die jungen M\u00e4dels heutzutage, aber eben okay. So um die 60 kg bei 169 K\u00f6rpergr\u00f6\u00dfe. Seit ich schilddr\u00fcsenkrank bin, ist mein Gewicht rapide nach oben geklettert bzw. seit der Einnahme der Schilddr\u00fcsenhormone stagniert es auf hohem Niveau. Heute dann der Schock. Ich war in der Stadt bei H &amp; M und wollte mir einen Rock kaufen. Um genau zu sein den hier, in schwarz, Gr\u00f6\u00dfe 44. Wirklich sch\u00f6n! Aber ich habe ihn nur noch mit M\u00fch und Not \u00fcberhaupt zugekriegt. Dabei ist das Material stretchig. Erst wollte ich ihn eine Nummer gr\u00f6\u00dfer nehmen, doch dann habe ich gedacht, jetzt ist Schlu\u00df!!! Obwohl er mir nicht richtig passt, habe ich ihn trotzdem gekauft. Gewissermassen als Anreiz. Wie lange es dauert bis der Rock gut sitzt, weiss ich zwar nicht, aber eins weiss ich, ab heute nehme ich ab!!!<\/p>\n<p>Weitere Informationen zu meinen wissenschaftlich fundierten, gut strukturierten und leicht verst\u00e4ndlichen Patientenratgebern erhalten Sie, wenn Sie auf die Grafik klicken &#8230;<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/ebooks\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-17298 size-full\" src=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-content\/uploads\/2025\/07\/E-Book-Reihe-Diagnose-Hashimoto-Thyreoiditis.png\" alt=\"Buchcover und Kundenrezensionen zu den E-Books der Reihe &quot;Diagnose-Hashimoto-Thyreoiditis&quot;\" width=\"708\" height=\"514\" srcset=\"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-content\/uploads\/2025\/07\/E-Book-Reihe-Diagnose-Hashimoto-Thyreoiditis.png 708w, https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-content\/uploads\/2025\/07\/E-Book-Reihe-Diagnose-Hashimoto-Thyreoiditis-300x218.png 300w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/a><\/p>\n<h2><strong>Abnehmen im Schneckentempo &#8211; nur 1 kg in vier Wochen<\/strong><\/h2>\n<p><strong>18.03.12 <\/strong>Ich versuche jetzt seit \u00fcber einem Monat Di\u00e4t zu halten. Bisher aber leider nur mit sehr m\u00e4ssigem Erfolg. Ich habe lediglich ein einziges Kilogramm abgenommen. Irgendwie hatte ich mir das dann doch einfacher vorgestellt. Bei jedem noch so winzigen St\u00fcckchen Schokolade hatte ich ein schlechtes Gewissen, tags\u00fcber war mir nicht selten schwummerig und abends konnte ich nicht einschlafen, weil mir sooo der Magen geknurrt hat. Und wof\u00fcr die ganze Qu\u00e4lerei? F\u00fcr ein j\u00e4mmerliches Kilogramm weniger. Aber gut. Diese Woche habe ich angefangen mich zus\u00e4tzlich mehr zu bewegen. Wahrscheinlich entspreche ich jedem Vorurteil, denn ich bin nicht nur \u00fcbergewichtig, sondern auch nicht sonderlich sportlich. Lange Spazierg\u00e4nge (so ein bis zwei Stunden) und etwas l\u00e4ngere Fahrradtouren von vielleicht 30 km \u2013 mehr ist nicht drin. Schon den Sportunterricht in der Schule habe ich gehasst. Ich fand es immer besonders eklig, dass man sich danach ohne zu Duschen direkt anzog und dann wieder verschwitzt und nach Schwei\u00df riechend im Unterricht sa\u00df. Na, wenigstens die Zeiten sind vorbei.<\/p>\n<h2><strong>Ges\u00fcnder essen + mehr Bewegung = Gewichtszunahme<\/strong><\/h2>\n<p><strong>03.04.12 <\/strong>Heute bin ich echt genervt. Seit beinahe sieben Wochen versuche ich jetzt abzunehmen. Ich habe deutlich ges\u00fcnder, kalorien\u00e4rmer und auch weniger gegessen. Seit drei Wochen habe ich mich zus\u00e4tzlich mehr bewegt, d.h. ich bin ausnahmslos jeden Tag (!) mindestens f\u00fcnf und manchmal sogar zehn Kilometer spazieren gegangen. Ja, ich weiss, dass ist kein Sport. Aber wenn man vorher nichts gemacht hat, sollte man dadurch doch zumindest irgendeine Ver\u00e4nderung sp\u00fcren. Bei mir ist aber nichts passiert. Oder doch, getan hat sich schon etwas. Allerdings nicht wie erwartet. Ich habe n\u00e4mlich 0,5 Kilogramm zugenommen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle auf www.schilddruesenguide.de bisher ver\u00f6ffentlichten Erfahrungsberichte von Hashimoto-Patientinnen: Andrea, Annette, Barbara, Britta, Katja, Sara, Susanne &#8211; falls sie auch bereit sind Ihre Geschichte aufzuschreiben, melden Sie sich gern per E-Mail.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_metis_text_type":"standard","_metis_text_length":3540,"_post_count":0,"footnotes":""},"categories":[5,1550],"tags":[104,1713,93,53,110,1857],"class_list":["post-674","post","type-post","status-publish","format-standard","hentry","category-hashimoto-thyreoiditis","category-schilddruese-ernaehrung-nahrungsergaenzung-gewichtsprobleme","tag-104","tag-abnehmen-mit-hashimoto","tag-erfahrungsbericht","tag-gastartikel","tag-ht","tag-schilddruese-gewicht"],"_links":{"self":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts\/674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/comments?post=674"}],"version-history":[{"count":0,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts\/674\/revisions"}],"wp:attachment":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/media?parent=674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/categories?post=674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/tags?post=674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}