{"id":186,"date":"2015-08-11T06:45:22","date_gmt":"2015-08-11T04:45:22","guid":{"rendered":"http:\/\/schilddruesenguide.de\/thyreoiditis\/?p=186"},"modified":"2023-09-16T11:02:28","modified_gmt":"2023-09-16T09:02:28","slug":"hypothyreose-im-wirrwarr-der-wechselwirkungen","status":"publish","type":"post","link":"https:\/\/schilddruesenguide.de\/thyreoiditis\/hypothyreose-im-wirrwarr-der-wechselwirkungen\/","title":{"rendered":"Hypothyreose: Im Wirrwarr der Wechselwirkungen"},"content":{"rendered":"<p><strong>F\u00fcr Schilddr\u00fcsenpatientInnen ist es wichtig alle behandelnden \u00c4rztInnen darauf hinzuweisen, dass sie ein Schilddr\u00fcsenhormonpr\u00e4parat einnehmen.<\/strong><\/p>\n<p>Es gibt eine ganze Reihe von Medikamenten, pflanzlichen Pr\u00e4paraten (z.B. Sonnenhut, Mistel) und Nahrungserg\u00e4nzungsmitteln (z.B. Eisen, Calcium, Jod), die in den Schilddr\u00fcsenhormonstoffwechsel eingreifen oder bei deren Einnahme es zu Wechselwirkungen mit Levothyroxinnatrium (k\u00fcnstlich hergestelltes Schilddr\u00fcsenhormon) kommt. PatientInnen die Schilddr\u00fcsenhormonpr\u00e4parate einnehmen sollten sich im Zweifelsfall an ihren Arzt oder Apotheker wenden.<\/p>\n<p>Einen sehr guten Artikel zu den Wechselwirkungen von Schilddr\u00fcsenhormonen mit anderen Medikamenten, aber auch den unterschiedlichen Lebensmitteln wurde aktuell unter dem Titel &#8222;Hypothyreose: Im Wirrwarr der Wechselwirkungen&#8220; (<span style=\"color: #ff0000;\">defekter Link wurde am 13.09.23 gel\u00f6scht<\/span>) bei den Doccheck-News ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr Schilddr\u00fcsenpatientInnen ist es wichtig alle behandelnden \u00c4rztInnen darauf hinzuweisen, dass sie ein Schilddr\u00fcsenhormonpr\u00e4parat einnehmen. Es gibt eine ganze Reihe von Medikamenten, pflanzlichen Pr\u00e4paraten (z.B. Sonnenhut, Mistel) und Nahrungserg\u00e4nzungsmitteln (z.B. Eisen, Calcium, Jod), die in den Schilddr\u00fcsenhormonstoffwechsel eingreifen oder bei deren Einnahme es zu Wechselwirkungen mit Levothyroxinnatrium (k\u00fcnstlich hergestelltes Schilddr\u00fcsenhormon) [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"link","meta":{"_metis_text_type":"","_metis_text_length":907,"_post_count":0,"footnotes":""},"categories":[9],"tags":[695,174,693,694],"class_list":["post-186","post","type-post","status-publish","format-link","hentry","category-schilddruese-allgemein","tag-medikamente","tag-schilddruesenhormone","tag-schilddruesenstoffwechsel","tag-wechselwirkungen","post_format-post-format-link"],"_links":{"self":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":0,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"wp:attachment":[{"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/schilddruesenguide.de\/thyreoiditis\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}